{"id":460,"date":"2025-03-21T23:42:25","date_gmt":"2025-03-21T23:42:25","guid":{"rendered":"https:\/\/debateexperts.com\/la-double-victoire-de-sasha-kay-lindo-au-barkley-forum-2025-confirme-sa-celebrite-dans-le-domaine-des-debats-au-lycee\/"},"modified":"2025-04-14T16:46:52","modified_gmt":"2025-04-14T16:46:52","slug":"la-double-victoire-de-sasha-kay-lindo-au-barkley-forum-2025-confirme-sa-celebrite-dans-le-domaine-des-debats-au-lycee","status":"publish","type":"post","link":"https:\/\/debateexperts.com\/fr\/la-double-victoire-de-sasha-kay-lindo-au-barkley-forum-2025-confirme-sa-celebrite-dans-le-domaine-des-debats-au-lycee\/","title":{"rendered":"La double victoire de Sasha-Kay Lindo au Barkley Forum 2025 confirme sa c\u00e9l\u00e9brit\u00e9 dans le domaine des d\u00e9bats au lyc\u00e9e."},"content":{"rendered":"\n<p><em>Dans une extraordinaire d\u00e9monstration de talent, <strong>Sasha-Kay Lindo<\/strong>, 16 ans, de l&rsquo;American Heritage School (Broward Campus, FL), a remport\u00e9 <strong>deux titres de champion<\/strong> lors du 70e Forum annuel Barkley pour les \u00e9coles secondaires \u00e0 la fin du mois de janvier 2025. Lindo a remport\u00e9 \u00e0 la fois l&rsquo;<a href=\"http:\/\/ahschool.com\"><strong>interpr\u00e9tation dramatique<\/strong> et l&rsquo;<strong>interpr\u00e9tation orale de programme<\/strong><\/a> &#8211; un rare doubl\u00e9 r\u00e9alis\u00e9 sur un terrain de plus de 2 000 concurrents de plus de 200 \u00e9coles <\/em>.<\/p>\n\n<figure class=\"wp-block-pullquote\"><blockquote><p><em>Son exploit, r\u00e9alis\u00e9 lors de l&rsquo;un des plus prestigieux tournois de d\u00e9bats et de discours des lyc\u00e9es du pays, consolide le statut de Lindo en tant qu&rsquo;\u00e9toile montante et illustre le pouvoir de la narration dans les comp\u00e9titions de criminalistique.<\/em><\/p><\/blockquote><\/figure>\n\n<h2 class=\"wp-block-heading\">Une rare double performance en championnat<\/h2>\n\n<p>Remporter une seule \u00e9preuve au Forum Barkley est un honneur convoit\u00e9. Remporter <strong>deux \u00e9preuves<\/strong> est pratiquement in\u00e9dit &#8211; et pourtant, c&rsquo;est exactement ce qu&rsquo;a fait Sasha-Kay Lindo. Au <a href=\"http:\/\/barkleyforum.emory.edu\">Forum Barkley<\/a>, organis\u00e9 par l&rsquo;universit\u00e9 Emory \u00e0 Atlanta, Sasha-Kay Lindo a d&rsquo;abord remport\u00e9 le titre d&rsquo;<strong>interpr\u00e9tation dramatique (DI)<\/strong>, puis celui d&rsquo;<strong>interpr\u00e9tation orale de programme (POI<\/strong> ), balayant les \u00e9preuves finales des deux cat\u00e9gories. <\/p>\n\n<p>L&rsquo;interpr\u00e9tation dramatique est une \u00e9preuve d&rsquo;interpr\u00e9tation en solo au cours de laquelle les concurrents interpr\u00e8tent un extrait d&rsquo;une pi\u00e8ce de th\u00e9\u00e2tre ou d&rsquo;un r\u00e9cit, en faisant preuve de profondeur \u00e9motionnelle et de caract\u00e9risation. L&rsquo;interpr\u00e9tation orale de programme consiste \u00e0 tisser des liens th\u00e9matiques entre des morceaux de litt\u00e9rature (prose, po\u00e9sie, th\u00e9\u00e2tre) en une seule performance. Exceller dans l&rsquo;une ou l&rsquo;autre discipline exige des comp\u00e9tences exceptionnelles &#8211; ma\u00eetriser les deux, dans le m\u00eame tournoi, est un triomphe d&rsquo;une <strong>immense polyvalence<\/strong>.  <\/p>\n\n<p>La performance de Lindo a \u00e9t\u00e9 d\u00e9crite par les juges comme <strong>captivante et poignante<\/strong>. En choisissant une pi\u00e8ce traitant du traumatisme interg\u00e9n\u00e9rationnel, elle a incarn\u00e9 plusieurs personnages avec fluidit\u00e9, faisant passer le public du rire aux larmes en l&rsquo;espace de quelques minutes. Sa prestation soign\u00e9e et ses \u00e9motions authentiques lui ont permis de se d\u00e9marquer d&rsquo;un groupe d&rsquo;acteurs talentueux lors de la phase finale. Dans POI, Lindo a con\u00e7u un programme autour du th\u00e8me de l&rsquo;identit\u00e9 et de l&rsquo;acceptation de soi, m\u00ealant de mani\u00e8re experte la po\u00e9sie orale \u00e0 des extraits de m\u00e9moires. La cr\u00e9ativit\u00e9 et la coh\u00e9sion de son programme ont \u00e9t\u00e9 remarquables. \u00ab\u00a0Elle nous tenait dans la paume de sa main\u00a0\u00bb, a d\u00e9clar\u00e9 un entra\u00eeneur \u00e0 propos de la prestation de Lindo en finale de POI, notant qu&rsquo;elle passait d&rsquo;un personnage \u00e0 l&rsquo;autre et d&rsquo;une voix narrative \u00e0 l&rsquo;autre \u00ab\u00a0avec une ma\u00eetrise \u00e9poustouflante\u00a0\u00bb.       <\/p>\n\n<p>\u00c0 la fin de ce tour, il \u00e9tait clair pour les observateurs que Lindo avait probablement d\u00e9croch\u00e9 une autre premi\u00e8re place. En effet, \u00e0 l&rsquo;annonce des r\u00e9sultats, elle est mont\u00e9e deux fois sur sc\u00e8ne, remportant deux troph\u00e9es Key d&rsquo;or (la r\u00e9compense embl\u00e9matique du Forum Barkley) sous un tonnerre d&rsquo;applaudissements de la part de la foule. <\/p>\n\n<h2 class=\"wp-block-heading\">Triomphe au prestigieux Forum Barkley<\/h2>\n\n<p>La double victoire de Sasha-Kay Lindo s&rsquo;est produite lors de ce qui est consid\u00e9r\u00e9 comme l&rsquo;un des <strong>tournois lyc\u00e9ens les plus difficiles du pays<\/strong>. Le Barkley Forum for High Schools &#8211; qui s&rsquo;est tenu du 24 au 26 janvier 2025 &#8211; a rassembl\u00e9 plus de 2 000 comp\u00e9titeurs de plus de 200 \u00e9coles dans 28 \u00c9tats. <\/p>\n\n<p>L&rsquo;inscription \u00e0 ce tournoi est tr\u00e8s s\u00e9lective ; les \u00e9coles doivent poser leur candidature et seules celles qui ont un bon dossier sont invit\u00e9es, ce qui garantit l&rsquo;<strong>existence d&rsquo;une \u00e9lite<\/strong>. Les \u00e9preuves du forum Barkley couvrent les d\u00e9bats (politique, Lincoln-Douglas, forum public, d\u00e9bat du Congr\u00e8s) et les discours (y compris l&rsquo;interpr\u00e9tation et l&rsquo;\u00e9loquence originale, entre autres). Les \u00e9preuves finales se d\u00e9roulent traditionnellement sous la forme d&rsquo;une exposition devant un large public, ce qui rend les enjeux et la visibilit\u00e9 encore plus importants.  <\/p>\n\n<p>L&rsquo;American Heritage School (AHS) &#8211; l&rsquo;\u00e9cole de Lindo &#8211; est une puissance permanente en mati\u00e8re de discours et de d\u00e9bats, et au Forum Barkley 2025, elle <strong>s&rsquo;est montr\u00e9e<\/strong> particuli\u00e8rement <strong>brillante<\/strong>. En fait, AHS a \u00e9t\u00e9 la <strong>seule \u00e9cole \u00e0 remporter plus d&rsquo;un titre de champion individuel<\/strong> lors du tournoi. <\/p>\n\n<p>Ce r\u00e9sultat est d\u00fb en grande partie \u00e0 l&rsquo;h\u00e9ro\u00efsme de Lindo dans deux cat\u00e9gories. Selon un communiqu\u00e9 de presse d&rsquo;American Heritage, l&rsquo;\u00e9quipe s&rsquo;est \u00e9galement targu\u00e9e d&rsquo;avoir plus de finalistes individuels dans toutes les \u00e9preuves que n&rsquo;importe quelle autre \u00e9cole pr\u00e9sente. <\/p>\n\n<p>Les directeurs du tournoi du Forum Barkley ont fait remarquer qu&rsquo;<strong>une telle double victoire est extr\u00eamement rare<\/strong>. Bien que les records de la ronde finale ne soient pas publi\u00e9s de mani\u00e8re exhaustive, des entra\u00eeneurs de longue date \u00e0 Emory ont attest\u00e9 que cela faisait de nombreuses ann\u00e9es qu&rsquo;un seul \u00e9tudiant n&rsquo;avait pas remport\u00e9 la premi\u00e8re place dans deux \u00e9preuves diff\u00e9rentes la m\u00eame ann\u00e9e. La plupart des comp\u00e9titeurs de haut niveau se sp\u00e9cialisent dans un seul genre ; le succ\u00e8s de Lindo dans plusieurs genres d\u00e9montre une \u00e9tendue de comp\u00e9tences que peu de gens peuvent \u00e9galer. Cela t\u00e9moigne \u00e9galement de son <strong>\u00e9thique de travail et de sa polyvalence<\/strong>: elle a d\u00fb pr\u00e9parer deux programmes distincts (d&rsquo;une dur\u00e9e de 10 minutes chacun) et passer plusieurs tours d&rsquo;\u00e9limination dans chaque \u00e9preuve, souvent l&rsquo;un apr\u00e8s l&rsquo;autre. Au cours de la derni\u00e8re journ\u00e9e du tournoi, Lindo a \u00e9t\u00e9 vue en <strong>train de sprinter<\/strong> litt\u00e9ralement <strong>entre les tours<\/strong>: elle s&rsquo;est produite dans le tour final DI et s&rsquo;est ensuite imm\u00e9diatement dirig\u00e9e vers les finales POI. Le fait qu&rsquo;elle ait pu maintenir un niveau aussi \u00e9lev\u00e9 dans les deux cas t\u00e9moigne de son endurance et de son sang-froid sous pression.     <\/p>\n\n<h2 class=\"wp-block-heading\">L&rsquo;art de raconter des histoires : Les points forts de Lindo<\/h2>\n\n<p>Qu&rsquo;est-ce qui fait de Sasha-Kay Lindo une concurrente si redoutable ? Les entra\u00eeneurs et les juges soulignent sa <strong>capacit\u00e9 exceptionnelle \u00e0 raconter des histoires<\/strong> et sa pr\u00e9sence sur sc\u00e8ne. En interpr\u00e9tation dramatique, elle fait preuve d&rsquo;une maturit\u00e9 qui d\u00e9passe son \u00e2ge &#8211; son travail sur les personnages est nuanc\u00e9 et elle n&rsquo;a pas peur de s&rsquo;attaquer \u00e0 des sujets complexes et lourds. Au Forum Barkley, alors que certains finalistes de l&rsquo;interpr\u00e9tation dramatique ont opt\u00e9 pour des pi\u00e8ces comiques ou des monologues dramatiques bien connus, Lindo a choisi une pi\u00e8ce relativement obscure qui a remis en question les perspectives de l&rsquo;auditoire. Le risque a \u00e9t\u00e9 payant : les juges l&rsquo;ont f\u00e9licit\u00e9e d&rsquo;avoir apport\u00e9 un nouveau r\u00e9cit sur sc\u00e8ne et de l&rsquo;avoir pr\u00e9sent\u00e9 avec conviction.    <\/p>\n\n<p>Dans le domaine de l&rsquo;interpr\u00e9tation orale de programme, la force de Lindo r\u00e9side dans l&rsquo;<strong>int\u00e9gration harmonieuse et la clart\u00e9 de la voix narrative<\/strong>. Construire un programme d&rsquo;IOP, c&rsquo;est comme mettre en sc\u00e8ne un spectacle individuel ; il faut s\u00e9lectionner des textes divers et trouver un fil conducteur. Le programme de Lindo, intitul\u00e9 <em>\u00ab\u00a0Pieces of Me\u00a0\u00bb,<\/em> m\u00eale un po\u00e8me moderne sur l&rsquo;image de soi, des dialogues tir\u00e9s d&rsquo;une pi\u00e8ce de th\u00e9\u00e2tre sur une adolescente \u00e0 la recherche de son identit\u00e9 culturelle, et des lignes tir\u00e9es de l&rsquo;histoire d&rsquo;un c\u00e9l\u00e8bre romancier sur le passage \u00e0 l&rsquo;\u00e2ge adulte. \u00c0 la fin du programme, ces pi\u00e8ces racontaient collectivement <em>son<\/em> histoire &#8211; ou une histoire qui lui semblait intimement sienne. Les juges ont soulign\u00e9 la coh\u00e9rence et la force \u00e9motionnelle de son programme, et un bulletin de vote a d\u00e9clar\u00e9 que sa performance \u00ab\u00a0a \u00e9tabli un nouveau standard pour ce que la POI peut \u00eatre\u00a0\u00bb.    <\/p>\n\n<p>Tout aussi importantes, les comp\u00e9tences techniques de Lindo sont de premier ordre. Elle \u00e9nonce clairement, utilise efficacement les pauses et a recours \u00e0 des gestes et des expressions faciales qui mettent en valeur plut\u00f4t qu&rsquo;ils ne d\u00e9tournent l&rsquo;attention. Ses transitions entre les personnages dans DI, ou entre les pi\u00e8ces dans POI, sont douces comme de la soie. D&rsquo;autres concurrents ont fait remarquer que <strong>lorsque Sasha-Kay se produit, on oublie qu&rsquo;on assiste \u00e0 un concours<\/strong> &#8211; elle cr\u00e9e une exp\u00e9rience th\u00e9\u00e2trale. C&rsquo;est cette capacit\u00e9 \u00e0 s&rsquo;immerger totalement dans la mati\u00e8re qui lui permet de marquer des points dans les \u00e9preuves d&rsquo;interpr\u00e9tation, o\u00f9 l&rsquo;objectif est d&rsquo;\u00e9mouvoir le public.    <\/p>\n\n<p>Malgr\u00e9 l&rsquo;immense pression, ceux qui ont vu Lindo \u00e0 Emory ont remarqu\u00e9 son <strong>calme et son humilit\u00e9<\/strong>. Apr\u00e8s sa victoire, elle s&rsquo;est empress\u00e9e de f\u00e9liciter les autres. \u00ab\u00a0C&rsquo;est un travail d&rsquo;\u00e9quipe\u00a0\u00bb, a-t-elle d\u00e9clar\u00e9 en remerciant ses entra\u00eeneurs et ses co\u00e9quipiers qui l&rsquo;ont aid\u00e9e \u00e0 r\u00e9p\u00e9ter ses morceaux. Cette gentillesse, associ\u00e9e \u00e0 son talent, a fait d&rsquo;elle une figure appr\u00e9ci\u00e9e, m\u00eame dans les \u00e9coles rivales. \u00ab\u00a0Tout le monde l&rsquo;acclamait \u00e0 la fin\u00a0\u00bb, se souvient un \u00e9l\u00e8ve d&rsquo;une \u00e9quipe concurrente, en r\u00e9f\u00e9rence au moment o\u00f9 la deuxi\u00e8me victoire de Lindo a \u00e9t\u00e9 annonc\u00e9e. \u00ab\u00a0Nous savions tous que nous avions assist\u00e9 \u00e0 quelque chose de sp\u00e9cial.     <\/p>\n\n<h2 class=\"wp-block-heading\">Une \u00e9toile montante et ce qui l&rsquo;attend<\/h2>\n\n<p>En remportant deux titres au Barkley Forum 2025, Sasha-Kay Lindo a \u00e9tabli une <strong>nouvelle r\u00e9f\u00e9rence en mati\u00e8re d&rsquo;excellence<\/strong> dans le domaine de l&rsquo;art oratoire au niveau du lyc\u00e9e. Cet exploit la propulse sous les feux de la rampe nationale comme l&rsquo;une des meilleures performeuses \u00e0 suivre cette ann\u00e9e. En tant que junior (11e ann\u00e9e), Sasha-Kay Lindo a encore le reste de la saison &#8211; et potentiellement sa derni\u00e8re ann\u00e9e &#8211; pour continuer \u00e0 gagner. Sa double victoire lui garantit pratiquement une participation au Tournoi des champions (TOC) en DI et POI, et elle sera sans aucun doute l&rsquo;une des <strong>favorites du TOC<\/strong> \u00e0 Lexington, Kentucky, au printemps.   <\/p>\n\n<p>Les entra\u00eeneurs d&rsquo;American Heritage consid\u00e8rent d\u00e9j\u00e0 Lindo comme un talent g\u00e9n\u00e9rationnel. \u00ab\u00a0Elle est le genre d&rsquo;\u00e9tudiante qui n&rsquo;arrive qu&rsquo;une fois par d\u00e9cennie, voire jamais\u00a0\u00bb, a d\u00e9clar\u00e9 l&rsquo;un d&rsquo;entre eux. Mais le succ\u00e8s de Lindo refl\u00e8te \u00e9galement la force du programme de son \u00e9quipe. L&rsquo;American Heritage Broward Campus investit beaucoup dans les discours et les d\u00e9bats, et les succ\u00e8s nationaux constants de ses \u00e9tudiants (dont plusieurs finalistes et champions au Barkley Forum) t\u00e9moignent de cette culture de l&rsquo;excellence.   <\/p>\n\n<p>Lindo a b\u00e9n\u00e9fici\u00e9 du mentorat de ses co\u00e9quipi\u00e8res plus \u00e2g\u00e9es au cours des ann\u00e9es pass\u00e9es, et aujourd&rsquo;hui, elle a pris la t\u00eate de l&rsquo;\u00e9quipe. Lors des entra\u00eenements de l&rsquo;\u00e9quipe, elle aide souvent les plus jeunes avec leurs pi\u00e8ces &#8211; une ironie du sort, \u00e9tant donn\u00e9 qu&rsquo;\u00e0 16 ans, elle est maintenant une double championne que d&rsquo;autres aspirent \u00e0 imiter. <\/p>\n\n<p>L&rsquo;ensemble de la communaut\u00e9 de l&rsquo;art oratoire et du d\u00e9bat l&rsquo;a \u00e9galement remarqu\u00e9. Des vid\u00e9os des performances de Lindo ont circul\u00e9 (avec autorisation) dans des forums et des ateliers de coaching. Son programme POI, en particulier, est utilis\u00e9 comme <strong>exemple d&rsquo;enseignement sur<\/strong> la mani\u00e8re de construire un programme th\u00e9matiquement fort. D&rsquo;une certaine mani\u00e8re, Lindo influence d\u00e9j\u00e0 la fa\u00e7on dont d&rsquo;autres \u00e9tudiants abordent leur m\u00e9tier.   <\/p>\n\n<p>Pour ce qui est de l&rsquo;avenir, Mme Lindo reste fid\u00e8le \u00e0 ses principes. Dans les interviews, elle souligne que pour elle, la parole est une question de connexion et de d\u00e9veloppement personnel. Les troph\u00e9es sont un bonus. Cet \u00e9tat d&rsquo;esprit correspond \u00e0 l&rsquo;\u00e9thique du Forum Barkley, qui c\u00e9l\u00e8bre \u00ab\u00a0l&rsquo;excellence judiciaire\u00a0\u00bb, mais aussi la camaraderie et la valeur \u00e9ducative de l&rsquo;activit\u00e9   <\/p>\n\n<p>Au cours de la saison 2024-25, tous les regards seront tourn\u00e9s vers Sasha-Kay Lindo. Qu&rsquo;elle joue une sc\u00e8ne dramatique ou qu&rsquo;elle livre un programme po\u00e9tique, elle a prouv\u00e9 qu&rsquo;elle pouvait commander une salle comme peu d&rsquo;autres personnes de son \u00e2ge. <strong>Remporter deux \u00e9preuves lors d&rsquo;un tournoi<\/strong> aussi prestigieux que le Barkley Forum est un exploit dont on se souviendra pendant des ann\u00e9es dans l&rsquo;histoire des discours et des d\u00e9bats des lyc\u00e9es. Et pour Lindo elle-m\u00eame, ce n&rsquo;est peut-\u00eatre que le d\u00e9but d&rsquo;un parcours illustre. Gr\u00e2ce \u00e0 son talent, \u00e0 son d\u00e9vouement et \u00e0 son sang-froid, cette jeune double championne est pr\u00eate \u00e0 laisser une marque ind\u00e9l\u00e9bile dans le monde de la comp\u00e9tition m\u00e9dico-l\u00e9gale &#8211; une performance puissante \u00e0 la fois.   <\/p>\n","protected":false},"excerpt":{"rendered":"<p>Dans une extraordinaire d\u00e9monstration de talent, Sasha-Kay Lindo, 16 ans, de l&rsquo;American Heritage School (Broward Campus, FL) a remport\u00e9 deux titres de champion lors du 70e Forum annuel Barkley pour les \u00e9coles secondaires \u00e0 la fin du mois de janvier 2025.  <\/p>\n","protected":false},"author":1,"featured_media":451,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_coblocks_attr":"","_coblocks_dimensions":"","_coblocks_responsive_height":"","_coblocks_accordion_ie_support":"","_kadence_starter_templates_imported_post":false,"_kad_post_transparent":"","_kad_post_title":"","_kad_post_layout":"","_kad_post_sidebar_id":"","_kad_post_content_style":"","_kad_post_vertical_padding":"","_kad_post_feature":"","_kad_post_feature_position":"","_kad_post_header":false,"_kad_post_footer":false,"_kad_post_classname":"","footnotes":""},"categories":[44],"tags":[46,48,45,49],"class_list":["post-460","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-actualites-et-coups-de-projecteur","tag-concours-de-debat","tag-debat-au-lycee","tag-evenement-de-debat","tag-forum-barkley"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>La double victoire de Sasha-Kay Lindo au Barkley Forum 2025 confirme sa c\u00e9l\u00e9brit\u00e9 dans le domaine des d\u00e9bats au lyc\u00e9e. - Debate Experts<\/title>\n<meta name=\"description\" content=\"Sasha-Kay Lindo de l&#039;American Heritage School a remport\u00e9 deux titres de champion lors du 70e Forum annuel Barkley \u00e0 la fin du mois de janvier 2025.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/debateexperts.com\/fr\/la-double-victoire-de-sasha-kay-lindo-au-barkley-forum-2025-confirme-sa-celebrite-dans-le-domaine-des-debats-au-lycee\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"La double victoire de Sasha-Kay Lindo au Barkley Forum 2025 confirme sa c\u00e9l\u00e9brit\u00e9 dans le domaine des d\u00e9bats au lyc\u00e9e. - Debate Experts\" \/>\n<meta property=\"og:description\" content=\"Sasha-Kay Lindo de l&#039;American Heritage School a remport\u00e9 deux titres de champion lors du 70e Forum annuel Barkley \u00e0 la fin du mois de janvier 2025.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/debateexperts.com\/fr\/la-double-victoire-de-sasha-kay-lindo-au-barkley-forum-2025-confirme-sa-celebrite-dans-le-domaine-des-debats-au-lycee\/\" \/>\n<meta property=\"og:site_name\" content=\"Debate Experts\" \/>\n<meta property=\"article:published_time\" content=\"2025-03-21T23:42:25+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2025-04-14T16:46:52+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/debateexperts.com\/wp-content\/uploads\/2025\/03\/BFHSlogoshield.png\" \/>\n\t<meta property=\"og:image:width\" content=\"1353\" \/>\n\t<meta property=\"og:image:height\" content=\"1432\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"55158pwpadmin\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"55158pwpadmin\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"10 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/debateexperts.com\\\/fr\\\/la-double-victoire-de-sasha-kay-lindo-au-barkley-forum-2025-confirme-sa-celebrite-dans-le-domaine-des-debats-au-lycee\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/debateexperts.com\\\/fr\\\/la-double-victoire-de-sasha-kay-lindo-au-barkley-forum-2025-confirme-sa-celebrite-dans-le-domaine-des-debats-au-lycee\\\/\"},\"author\":{\"name\":\"55158pwpadmin\",\"@id\":\"https:\\\/\\\/debateexperts.com\\\/fr\\\/#\\\/schema\\\/person\\\/fc31301f6b0605d8f6a356c045882f7b\"},\"headline\":\"La double victoire de Sasha-Kay Lindo au Barkley Forum 2025 confirme sa c\u00e9l\u00e9brit\u00e9 dans le domaine des d\u00e9bats au lyc\u00e9e.\",\"datePublished\":\"2025-03-21T23:42:25+00:00\",\"dateModified\":\"2025-04-14T16:46:52+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/debateexperts.com\\\/fr\\\/la-double-victoire-de-sasha-kay-lindo-au-barkley-forum-2025-confirme-sa-celebrite-dans-le-domaine-des-debats-au-lycee\\\/\"},\"wordCount\":2180,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/debateexperts.com\\\/fr\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/debateexperts.com\\\/fr\\\/la-double-victoire-de-sasha-kay-lindo-au-barkley-forum-2025-confirme-sa-celebrite-dans-le-domaine-des-debats-au-lycee\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/debateexperts.com\\\/wp-content\\\/uploads\\\/2025\\\/03\\\/BFHSlogoshield.png\",\"keywords\":[\"concours de d\u00e9bat\",\"d\u00e9bat au lyc\u00e9e\",\"\u00e9v\u00e9nement de d\u00e9bat\",\"forum barkley\"],\"articleSection\":[\"Actualit\u00e9s et coups de projecteur\"],\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/debateexperts.com\\\/fr\\\/la-double-victoire-de-sasha-kay-lindo-au-barkley-forum-2025-confirme-sa-celebrite-dans-le-domaine-des-debats-au-lycee\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/debateexperts.com\\\/fr\\\/la-double-victoire-de-sasha-kay-lindo-au-barkley-forum-2025-confirme-sa-celebrite-dans-le-domaine-des-debats-au-lycee\\\/\",\"url\":\"https:\\\/\\\/debateexperts.com\\\/fr\\\/la-double-victoire-de-sasha-kay-lindo-au-barkley-forum-2025-confirme-sa-celebrite-dans-le-domaine-des-debats-au-lycee\\\/\",\"name\":\"La double victoire de Sasha-Kay Lindo au Barkley Forum 2025 confirme sa c\u00e9l\u00e9brit\u00e9 dans le domaine des d\u00e9bats au lyc\u00e9e. - Debate Experts\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/debateexperts.com\\\/fr\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/debateexperts.com\\\/fr\\\/la-double-victoire-de-sasha-kay-lindo-au-barkley-forum-2025-confirme-sa-celebrite-dans-le-domaine-des-debats-au-lycee\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/debateexperts.com\\\/fr\\\/la-double-victoire-de-sasha-kay-lindo-au-barkley-forum-2025-confirme-sa-celebrite-dans-le-domaine-des-debats-au-lycee\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/debateexperts.com\\\/wp-content\\\/uploads\\\/2025\\\/03\\\/BFHSlogoshield.png\",\"datePublished\":\"2025-03-21T23:42:25+00:00\",\"dateModified\":\"2025-04-14T16:46:52+00:00\",\"description\":\"Sasha-Kay Lindo de l'American Heritage School a remport\u00e9 deux titres de champion lors du 70e Forum annuel Barkley \u00e0 la fin du mois de janvier 2025.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/debateexperts.com\\\/fr\\\/la-double-victoire-de-sasha-kay-lindo-au-barkley-forum-2025-confirme-sa-celebrite-dans-le-domaine-des-debats-au-lycee\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/debateexperts.com\\\/fr\\\/la-double-victoire-de-sasha-kay-lindo-au-barkley-forum-2025-confirme-sa-celebrite-dans-le-domaine-des-debats-au-lycee\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/debateexperts.com\\\/fr\\\/la-double-victoire-de-sasha-kay-lindo-au-barkley-forum-2025-confirme-sa-celebrite-dans-le-domaine-des-debats-au-lycee\\\/#primaryimage\",\"url\":\"https:\\\/\\\/debateexperts.com\\\/wp-content\\\/uploads\\\/2025\\\/03\\\/BFHSlogoshield.png\",\"contentUrl\":\"https:\\\/\\\/debateexperts.com\\\/wp-content\\\/uploads\\\/2025\\\/03\\\/BFHSlogoshield.png\",\"width\":1353,\"height\":1432},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/debateexperts.com\\\/fr\\\/la-double-victoire-de-sasha-kay-lindo-au-barkley-forum-2025-confirme-sa-celebrite-dans-le-domaine-des-debats-au-lycee\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/debateexperts.com\\\/fr\\\/accueil\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"La double victoire de Sasha-Kay Lindo au Barkley Forum 2025 confirme sa c\u00e9l\u00e9brit\u00e9 dans le domaine des d\u00e9bats au lyc\u00e9e.\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/debateexperts.com\\\/fr\\\/#website\",\"url\":\"https:\\\/\\\/debateexperts.com\\\/fr\\\/\",\"name\":\"Debate Experts\",\"description\":\"Debate Experts \u2013 Elevate Your Skills, Master Competitive Debate, and Grow Your Influence.\",\"publisher\":{\"@id\":\"https:\\\/\\\/debateexperts.com\\\/fr\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/debateexperts.com\\\/fr\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/debateexperts.com\\\/fr\\\/#organization\",\"name\":\"Debate Experts\",\"url\":\"https:\\\/\\\/debateexperts.com\\\/fr\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/debateexperts.com\\\/fr\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/debateexperts.com\\\/wp-content\\\/uploads\\\/2025\\\/03\\\/cropped-cropped-Debate-1.png\",\"contentUrl\":\"https:\\\/\\\/debateexperts.com\\\/wp-content\\\/uploads\\\/2025\\\/03\\\/cropped-cropped-Debate-1.png\",\"width\":356,\"height\":200,\"caption\":\"Debate Experts\"},\"image\":{\"@id\":\"https:\\\/\\\/debateexperts.com\\\/fr\\\/#\\\/schema\\\/logo\\\/image\\\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/debateexperts.com\\\/fr\\\/#\\\/schema\\\/person\\\/fc31301f6b0605d8f6a356c045882f7b\",\"name\":\"55158pwpadmin\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/ecbdd69171b85e0565bf188ef2056e55cc2dda46a7a29cd55fd48d0ba675fc29?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/ecbdd69171b85e0565bf188ef2056e55cc2dda46a7a29cd55fd48d0ba675fc29?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/ecbdd69171b85e0565bf188ef2056e55cc2dda46a7a29cd55fd48d0ba675fc29?s=96&d=mm&r=g\",\"caption\":\"55158pwpadmin\"},\"sameAs\":[\"https:\\\/\\\/debateexperts.com\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"La double victoire de Sasha-Kay Lindo au Barkley Forum 2025 confirme sa c\u00e9l\u00e9brit\u00e9 dans le domaine des d\u00e9bats au lyc\u00e9e. - Debate Experts","description":"Sasha-Kay Lindo de l'American Heritage School a remport\u00e9 deux titres de champion lors du 70e Forum annuel Barkley \u00e0 la fin du mois de janvier 2025.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/debateexperts.com\/fr\/la-double-victoire-de-sasha-kay-lindo-au-barkley-forum-2025-confirme-sa-celebrite-dans-le-domaine-des-debats-au-lycee\/","og_locale":"fr_FR","og_type":"article","og_title":"La double victoire de Sasha-Kay Lindo au Barkley Forum 2025 confirme sa c\u00e9l\u00e9brit\u00e9 dans le domaine des d\u00e9bats au lyc\u00e9e. - Debate Experts","og_description":"Sasha-Kay Lindo de l'American Heritage School a remport\u00e9 deux titres de champion lors du 70e Forum annuel Barkley \u00e0 la fin du mois de janvier 2025.","og_url":"https:\/\/debateexperts.com\/fr\/la-double-victoire-de-sasha-kay-lindo-au-barkley-forum-2025-confirme-sa-celebrite-dans-le-domaine-des-debats-au-lycee\/","og_site_name":"Debate Experts","article_published_time":"2025-03-21T23:42:25+00:00","article_modified_time":"2025-04-14T16:46:52+00:00","og_image":[{"width":1353,"height":1432,"url":"https:\/\/debateexperts.com\/wp-content\/uploads\/2025\/03\/BFHSlogoshield.png","type":"image\/png"}],"author":"55158pwpadmin","twitter_card":"summary_large_image","twitter_misc":{"\u00c9crit par":"55158pwpadmin","Dur\u00e9e de lecture estim\u00e9e":"10 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/debateexperts.com\/fr\/la-double-victoire-de-sasha-kay-lindo-au-barkley-forum-2025-confirme-sa-celebrite-dans-le-domaine-des-debats-au-lycee\/#article","isPartOf":{"@id":"https:\/\/debateexperts.com\/fr\/la-double-victoire-de-sasha-kay-lindo-au-barkley-forum-2025-confirme-sa-celebrite-dans-le-domaine-des-debats-au-lycee\/"},"author":{"name":"55158pwpadmin","@id":"https:\/\/debateexperts.com\/fr\/#\/schema\/person\/fc31301f6b0605d8f6a356c045882f7b"},"headline":"La double victoire de Sasha-Kay Lindo au Barkley Forum 2025 confirme sa c\u00e9l\u00e9brit\u00e9 dans le domaine des d\u00e9bats au lyc\u00e9e.","datePublished":"2025-03-21T23:42:25+00:00","dateModified":"2025-04-14T16:46:52+00:00","mainEntityOfPage":{"@id":"https:\/\/debateexperts.com\/fr\/la-double-victoire-de-sasha-kay-lindo-au-barkley-forum-2025-confirme-sa-celebrite-dans-le-domaine-des-debats-au-lycee\/"},"wordCount":2180,"commentCount":0,"publisher":{"@id":"https:\/\/debateexperts.com\/fr\/#organization"},"image":{"@id":"https:\/\/debateexperts.com\/fr\/la-double-victoire-de-sasha-kay-lindo-au-barkley-forum-2025-confirme-sa-celebrite-dans-le-domaine-des-debats-au-lycee\/#primaryimage"},"thumbnailUrl":"https:\/\/debateexperts.com\/wp-content\/uploads\/2025\/03\/BFHSlogoshield.png","keywords":["concours de d\u00e9bat","d\u00e9bat au lyc\u00e9e","\u00e9v\u00e9nement de d\u00e9bat","forum barkley"],"articleSection":["Actualit\u00e9s et coups de projecteur"],"inLanguage":"fr-FR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/debateexperts.com\/fr\/la-double-victoire-de-sasha-kay-lindo-au-barkley-forum-2025-confirme-sa-celebrite-dans-le-domaine-des-debats-au-lycee\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/debateexperts.com\/fr\/la-double-victoire-de-sasha-kay-lindo-au-barkley-forum-2025-confirme-sa-celebrite-dans-le-domaine-des-debats-au-lycee\/","url":"https:\/\/debateexperts.com\/fr\/la-double-victoire-de-sasha-kay-lindo-au-barkley-forum-2025-confirme-sa-celebrite-dans-le-domaine-des-debats-au-lycee\/","name":"La double victoire de Sasha-Kay Lindo au Barkley Forum 2025 confirme sa c\u00e9l\u00e9brit\u00e9 dans le domaine des d\u00e9bats au lyc\u00e9e. - Debate Experts","isPartOf":{"@id":"https:\/\/debateexperts.com\/fr\/#website"},"primaryImageOfPage":{"@id":"https:\/\/debateexperts.com\/fr\/la-double-victoire-de-sasha-kay-lindo-au-barkley-forum-2025-confirme-sa-celebrite-dans-le-domaine-des-debats-au-lycee\/#primaryimage"},"image":{"@id":"https:\/\/debateexperts.com\/fr\/la-double-victoire-de-sasha-kay-lindo-au-barkley-forum-2025-confirme-sa-celebrite-dans-le-domaine-des-debats-au-lycee\/#primaryimage"},"thumbnailUrl":"https:\/\/debateexperts.com\/wp-content\/uploads\/2025\/03\/BFHSlogoshield.png","datePublished":"2025-03-21T23:42:25+00:00","dateModified":"2025-04-14T16:46:52+00:00","description":"Sasha-Kay Lindo de l'American Heritage School a remport\u00e9 deux titres de champion lors du 70e Forum annuel Barkley \u00e0 la fin du mois de janvier 2025.","breadcrumb":{"@id":"https:\/\/debateexperts.com\/fr\/la-double-victoire-de-sasha-kay-lindo-au-barkley-forum-2025-confirme-sa-celebrite-dans-le-domaine-des-debats-au-lycee\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/debateexperts.com\/fr\/la-double-victoire-de-sasha-kay-lindo-au-barkley-forum-2025-confirme-sa-celebrite-dans-le-domaine-des-debats-au-lycee\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/debateexperts.com\/fr\/la-double-victoire-de-sasha-kay-lindo-au-barkley-forum-2025-confirme-sa-celebrite-dans-le-domaine-des-debats-au-lycee\/#primaryimage","url":"https:\/\/debateexperts.com\/wp-content\/uploads\/2025\/03\/BFHSlogoshield.png","contentUrl":"https:\/\/debateexperts.com\/wp-content\/uploads\/2025\/03\/BFHSlogoshield.png","width":1353,"height":1432},{"@type":"BreadcrumbList","@id":"https:\/\/debateexperts.com\/fr\/la-double-victoire-de-sasha-kay-lindo-au-barkley-forum-2025-confirme-sa-celebrite-dans-le-domaine-des-debats-au-lycee\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/debateexperts.com\/fr\/accueil\/"},{"@type":"ListItem","position":2,"name":"La double victoire de Sasha-Kay Lindo au Barkley Forum 2025 confirme sa c\u00e9l\u00e9brit\u00e9 dans le domaine des d\u00e9bats au lyc\u00e9e."}]},{"@type":"WebSite","@id":"https:\/\/debateexperts.com\/fr\/#website","url":"https:\/\/debateexperts.com\/fr\/","name":"Debate Experts","description":"Debate Experts \u2013 Elevate Your Skills, Master Competitive Debate, and Grow Your Influence.","publisher":{"@id":"https:\/\/debateexperts.com\/fr\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/debateexperts.com\/fr\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/debateexperts.com\/fr\/#organization","name":"Debate Experts","url":"https:\/\/debateexperts.com\/fr\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/debateexperts.com\/fr\/#\/schema\/logo\/image\/","url":"https:\/\/debateexperts.com\/wp-content\/uploads\/2025\/03\/cropped-cropped-Debate-1.png","contentUrl":"https:\/\/debateexperts.com\/wp-content\/uploads\/2025\/03\/cropped-cropped-Debate-1.png","width":356,"height":200,"caption":"Debate Experts"},"image":{"@id":"https:\/\/debateexperts.com\/fr\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/debateexperts.com\/fr\/#\/schema\/person\/fc31301f6b0605d8f6a356c045882f7b","name":"55158pwpadmin","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/secure.gravatar.com\/avatar\/ecbdd69171b85e0565bf188ef2056e55cc2dda46a7a29cd55fd48d0ba675fc29?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/ecbdd69171b85e0565bf188ef2056e55cc2dda46a7a29cd55fd48d0ba675fc29?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/ecbdd69171b85e0565bf188ef2056e55cc2dda46a7a29cd55fd48d0ba675fc29?s=96&d=mm&r=g","caption":"55158pwpadmin"},"sameAs":["https:\/\/debateexperts.com"]}]}},"_links":{"self":[{"href":"https:\/\/debateexperts.com\/fr\/wp-json\/wp\/v2\/posts\/460","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/debateexperts.com\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/debateexperts.com\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/debateexperts.com\/fr\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/debateexperts.com\/fr\/wp-json\/wp\/v2\/comments?post=460"}],"version-history":[{"count":1,"href":"https:\/\/debateexperts.com\/fr\/wp-json\/wp\/v2\/posts\/460\/revisions"}],"predecessor-version":[{"id":466,"href":"https:\/\/debateexperts.com\/fr\/wp-json\/wp\/v2\/posts\/460\/revisions\/466"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/debateexperts.com\/fr\/wp-json\/wp\/v2\/media\/451"}],"wp:attachment":[{"href":"https:\/\/debateexperts.com\/fr\/wp-json\/wp\/v2\/media?parent=460"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/debateexperts.com\/fr\/wp-json\/wp\/v2\/categories?post=460"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/debateexperts.com\/fr\/wp-json\/wp\/v2\/tags?post=460"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}